{"id":13045,"date":"2022-04-29T15:44:22","date_gmt":"2022-04-29T15:44:22","guid":{"rendered":"http:\/\/casacristal.pt\/product\/quadro-pintado-coroacao-espirito-santo\/"},"modified":"2023-02-08T17:15:28","modified_gmt":"2023-02-08T17:15:28","slug":"quadro-pintado-coroacao-espirito-santo","status":"publish","type":"product","link":"https:\/\/casacristal.pt\/en\/product\/quadro-pintado-coroacao-espirito-santo\/","title":{"rendered":"Quadro Pintado Coroa\u00e7\u00e3o Esp\u00edrito Santo"},"content":{"rendered":"<p>Quadro Pintado Coroa\u00e7\u00e3o Esp\u00edrito Santo<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quadro Pintado Coroa\u00e7\u00e3o Esp\u00edrito Santo<\/p>\n","protected":false},"featured_media":13485,"template":"","meta":[],"product_cat":[369,430,426],"product_tag":[],"cat_produtos":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Quadro Pintado Coroa\u00e7\u00e3o Esp\u00edrito Santo - Casa Cristal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casacristal.pt\/en\/product\/quadro-pintado-coroacao-espirito-santo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Quadro Pintado Coroa\u00e7\u00e3o Esp\u00edrito Santo - Casa Cristal\" \/>\n<meta property=\"og:description\" content=\"Quadro Pintado Coroa\u00e7\u00e3o Esp\u00edrito Santo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casacristal.pt\/en\/product\/quadro-pintado-coroacao-espirito-santo\/\" \/>\n<meta property=\"og:site_name\" content=\"Casa Cristal\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-08T17:15:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casacristal.pt\/wp-content\/uploads\/imagens\/analisadas\/161BQU30-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"user\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/casacristal.pt\/#website\",\"url\":\"https:\/\/casacristal.pt\/\",\"name\":\"Casa Cristal\",\"description\":\"Artigo Religioso, Decora\u00e7\u00e3o e Utilidades dom\u00e9sticas e Hoteleiras - Ponta Delgada\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/casacristal.pt\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/casacristal.pt\/en\/product\/quadro-pintado-coroacao-espirito-santo\/#primaryimage\",\"url\":\"https:\/\/casacristal.pt\/wp-content\/uploads\/imagens\/analisadas\/161BQU30-scaled.jpg\",\"contentUrl\":\"https:\/\/casacristal.pt\/wp-content\/uploads\/imagens\/analisadas\/161BQU30-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/casacristal.pt\/en\/product\/quadro-pintado-coroacao-espirito-santo\/#webpage\",\"url\":\"https:\/\/casacristal.pt\/en\/product\/quadro-pintado-coroacao-espirito-santo\/\",\"name\":\"Quadro Pintado Coroa\u00e7\u00e3o Esp\u00edrito Santo - Casa Cristal\",\"isPartOf\":{\"@id\":\"https:\/\/casacristal.pt\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/casacristal.pt\/en\/product\/quadro-pintado-coroacao-espirito-santo\/#primaryimage\"},\"datePublished\":\"2022-04-29T15:44:22+00:00\",\"dateModified\":\"2023-02-08T17:15:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/casacristal.pt\/en\/product\/quadro-pintado-coroacao-espirito-santo\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/casacristal.pt\/en\/product\/quadro-pintado-coroacao-espirito-santo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/casacristal.pt\/en\/product\/quadro-pintado-coroacao-espirito-santo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/casacristal.pt\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Products\",\"item\":\"https:\/\/casacristal.pt\/en\/products\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Quadro Pintado Coroa\u00e7\u00e3o Esp\u00edrito Santo\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Quadro Pintado Coroa\u00e7\u00e3o Esp\u00edrito Santo - Casa Cristal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casacristal.pt\/en\/product\/quadro-pintado-coroacao-espirito-santo\/","og_locale":"en_US","og_type":"article","og_title":"Quadro Pintado Coroa\u00e7\u00e3o Esp\u00edrito Santo - Casa Cristal","og_description":"Quadro Pintado Coroa\u00e7\u00e3o Esp\u00edrito Santo","og_url":"https:\/\/casacristal.pt\/en\/product\/quadro-pintado-coroacao-espirito-santo\/","og_site_name":"Casa Cristal","article_modified_time":"2023-02-08T17:15:28+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/casacristal.pt\/wp-content\/uploads\/imagens\/analisadas\/161BQU30-scaled.jpg","type":"image\/jpeg"}],"author":"user","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/casacristal.pt\/#website","url":"https:\/\/casacristal.pt\/","name":"Casa Cristal","description":"Artigo Religioso, Decora\u00e7\u00e3o e Utilidades dom\u00e9sticas e Hoteleiras - Ponta Delgada","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casacristal.pt\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casacristal.pt\/en\/product\/quadro-pintado-coroacao-espirito-santo\/#primaryimage","url":"https:\/\/casacristal.pt\/wp-content\/uploads\/imagens\/analisadas\/161BQU30-scaled.jpg","contentUrl":"https:\/\/casacristal.pt\/wp-content\/uploads\/imagens\/analisadas\/161BQU30-scaled.jpg","width":2560,"height":1707},{"@type":"WebPage","@id":"https:\/\/casacristal.pt\/en\/product\/quadro-pintado-coroacao-espirito-santo\/#webpage","url":"https:\/\/casacristal.pt\/en\/product\/quadro-pintado-coroacao-espirito-santo\/","name":"Quadro Pintado Coroa\u00e7\u00e3o Esp\u00edrito Santo - Casa Cristal","isPartOf":{"@id":"https:\/\/casacristal.pt\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casacristal.pt\/en\/product\/quadro-pintado-coroacao-espirito-santo\/#primaryimage"},"datePublished":"2022-04-29T15:44:22+00:00","dateModified":"2023-02-08T17:15:28+00:00","breadcrumb":{"@id":"https:\/\/casacristal.pt\/en\/product\/quadro-pintado-coroacao-espirito-santo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casacristal.pt\/en\/product\/quadro-pintado-coroacao-espirito-santo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/casacristal.pt\/en\/product\/quadro-pintado-coroacao-espirito-santo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casacristal.pt\/en\/"},{"@type":"ListItem","position":2,"name":"Products","item":"https:\/\/casacristal.pt\/en\/products\/"},{"@type":"ListItem","position":3,"name":"Quadro Pintado Coroa\u00e7\u00e3o Esp\u00edrito Santo"}]}]}},"_links":{"self":[{"href":"https:\/\/casacristal.pt\/en\/wp-json\/wp\/v2\/product\/13045"}],"collection":[{"href":"https:\/\/casacristal.pt\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/casacristal.pt\/en\/wp-json\/wp\/v2\/types\/product"}],"version-history":[{"count":3,"href":"https:\/\/casacristal.pt\/en\/wp-json\/wp\/v2\/product\/13045\/revisions"}],"predecessor-version":[{"id":185475,"href":"https:\/\/casacristal.pt\/en\/wp-json\/wp\/v2\/product\/13045\/revisions\/185475"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casacristal.pt\/en\/wp-json\/wp\/v2\/media\/13485"}],"wp:attachment":[{"href":"https:\/\/casacristal.pt\/en\/wp-json\/wp\/v2\/media?parent=13045"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/casacristal.pt\/en\/wp-json\/wp\/v2\/product_cat?post=13045"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/casacristal.pt\/en\/wp-json\/wp\/v2\/product_tag?post=13045"},{"taxonomy":"cat_produtos","embeddable":true,"href":"https:\/\/casacristal.pt\/en\/wp-json\/wp\/v2\/cat_produtos?post=13045"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}